{"id":109,"date":"2014-01-01T00:00:11","date_gmt":"2013-12-31T23:00:11","guid":{"rendered":"https:\/\/www.chrenhart.eu\/2021\/?p=109"},"modified":"2021-06-27T12:26:25","modified_gmt":"2021-06-27T10:26:25","slug":"farben-des-mohns-2","status":"publish","type":"post","link":"https:\/\/www.chrenhart.eu\/2021\/2014\/01\/01\/farben-des-mohns-2\/","title":{"rendered":"Farben des Mohns"},"content":{"rendered":"\n<div class=\"wp-block-group alignfull has-primary-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-embed alignwide is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Farben des Mohns (Teil 1)\" width=\"580\" height=\"435\" src=\"https:\/\/www.youtube.com\/embed\/3IYmZ0vnuP8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><figcaption>Farben des Mohns | Klaudia Tandl (mezzo-soprano) | Christoph Renhart (piano)<\/figcaption><\/figure>\n<\/div><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Farben des Mohns<br>for mezzo-soprano and piano (2014)<\/h4>\n\n\n\n<p>Farben des Mohns entstand im Fr\u00fchjahr 2014 nach f\u00fcnf Gedichten von Jakob Reichs\u00f6llner. Ich erbat mir eine Art Lyrik, die ich motivisch verarbeiten, fragmentieren und die ich als musikalisches Material zusammen mit dem Klanguniversum des Klaviers zu einem neuen, eigenst\u00e4ndigen Werk verspinnen konnte. Kl\u00e4nge und Text sollten kammermusikalisch miteinander verschmelzen. Die Poesie aus der semantischen Bedeutung einzelner sprachlicher Momente sollte, in Musik gegossen, aus den Kl\u00e4ngen heraus sprechen. Das entstandene musikalische Werk ist gleichsam eine Interpretation der Gedichte, die darin einige Aspekte zutiefst emotional durchleuchtet und diese um eine akustische Perspektive erweitert.<\/p>\n\n\n\n<p>Das Klavierlied hat einen langen Weg hinter sich gelassen und tiefe Spurrillen in das Pflaster der Tradition gefurcht. Begegnen wir ihm heute, indem wir diesen Wagen ziehen lassen, seine Lenker werden neues Terrain erschlie\u00dfen, auf ihrer Reise neue Klangkulissen entdecken und die Art und Weise des Transportmittels best\u00e4ndig weiterentwickeln. Was von einstens geblieben ist, ist die Idee, zwei MusikerInnen \u2014 ein S\u00e4nger und ein Pianist \u2014 gemeinsam k\u00fcnstlerisch interagieren zu lassen.<\/p>\n\n\n\n<p>Insofern sehe ich in meinem Werk vielmehr die kammermusikalische Begegnung als Grundgedanke verwurzelt als die Patina eines herbeizitierten Geistes, der freilich nie mehr wiederkehrt. Diese Begegnung erf\u00e4hrt eine Erweiterung ihrer rein klanglichen Dimension durch ein fragil-szenisches Konzept, welches sich jedoch in einer kammermusikalischen Konzertsituation sehr gut realisieren l\u00e4sst.<\/p>\n\n\n\n<p>Der theatralische Aspekt des Werks wird durch die Einbeziehung und Beeinflussung des Raumlichtes einerseits sowie durch szenische Andeutungen der S\u00e4ngerin \u2014 die in der Partitur vorskizziert sind \u2014 andererseits etabliert. Dar\u00fcber hinaus tr\u00e4gt der\/die PianistIn durch ein gestenreiches Spiel \u2014 insbesondere die Einbeziehung des Innenraums des Instruments unterst\u00fctzt die Musik auch betont pantomimisch \u2014 zum theatralisch-expressiven Charakter des Werkes ma\u00dfgeblich bei.<\/p>\n\n\n\n<p>Mein Ziel war, dass die SpielerInnen die Musik und ihren semantischen Inhalt im besten Sinne des Wortes verk\u00f6rpern: Emotional, ausdrucksstark, gestenreich und in all der dazu notwendigen Gestaltungsfreiheit. Dazu muss die Musik in ihren Kl\u00e4ngen und in ihrer Notationsform Freir\u00e4ume schaffen, nicht alles restlos festlegen und doch dramaturgisch stringent durch die Kulissen get\u00fcrmter Klangpyramiden zu f\u00fchren verm\u00f6gen.<\/p>\n\n\n\n<p>H\u00f6ren wir also in Farben des Mohns die Stille des Rauschens, den obskuren Schein der Nacht und atmen wir neugierig die Schatten, die vom jenseitigen Ufer her hallen. Begleiten wir die Figuren, die am Grat der Welten wandeln, erf\u00fcllt von der Leere aus Leben und Tod. Lassen wir uns verf\u00fchren von den \u00bbgiftzartumm\u00e4ntelten\u00ab Gew\u00e4chsen eines verw\u00fcnschten Gartens und trotzen wir den Glocken, die fortw\u00e4hrend unser Schicksal einl\u00e4uten. \u2014 Christoph Renhart, Oktober 2015<\/p>\n\n\n\n<div class=\"wp-block-group alignfull boxtxt has-accent-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p>INSTRUMENTATION:<br>mezzo-soprano, piano<\/p>\n\n\n\n<p>DURATION:<br>13 minutes<\/p>\n\n\n\n<p>PERFORMANCE MATERIAL:<br>info@chrenhart.eu<\/p>\n\n\n\n<p>PREMIERE:<br>October 22, 2015&nbsp;\u2022 Maria Saal, Dom zu Maria Saal \u2022 Johanna von der Deken, mezzo-soprano \u2022 Gaiva Bandzinaite, piano<\/p>\n\n\n\n<p>PERFORMANCES:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>November 10, 2015&nbsp;\u2022 Graz, Palais Meran \u2022 Klaudia Tandl, mezzo-soprano \u2022 Christoph Renhart, piano<\/li><li>November 13, 2015&nbsp;\u2022 Graz, Steiermarkhof \u2022 Klaudia Tandl, mezzo-soprano \u2022 Christoph Renhart, piano <\/li><li>March 2, 2016&nbsp;\u2022 Graz, Palais Meran \u2022 Klaudia Tandl, mezzo-soprano \u2022 Christoph Renhart, piano <\/li><li>March 8, 2016&nbsp;\u2022 Salzburg, Mozarteum \u2022 Klaudia Tandl, mezzo-soprano \u2022 Christoph Renhart, piano <\/li><li>November 24, 2016&nbsp;\u2022 Weiz, Europasaal \u2022 Klaudia Tandl, mezzo-soprano \u2022 Christoph Renhart, piano <\/li><li>September 3, 2016&nbsp;\u2022 Radio Rai S\u00fcdtirol, Querschnitte \u2022 Klaudia Tandl, mezzo-soprano \u2022 Christoph Renhart, piano <\/li><li>January 21, 2017&nbsp;\u2022 Graz, Palais Meran \u2022 Klaudia Tandl, mezzo-soprano \u2022 Wolfgang Riegler-Sontacchi, piano <\/li><li>January 22, 2018&nbsp;\u2022 Radio \u00d61, Zeit-Ton \u2022 Klaudia Tandl, mezzo-soprano \u2022 Christoph Renhart, piano <\/li><li>January 28, 2018&nbsp;\u2022 Radio Steiermark, Kultur spezial \u2022 Klaudia Tandl, mezzo-soprano \u2022 Christoph Renhart, piano<\/li><\/ul>\n<\/div><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>for mezzo-soprano and piano (2014)<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[99,24,2],"tags":[14,59,18,85,113,118,112,54,111,74,120,122,119,116,32,124,115,121,117,123,114],"class_list":["post-109","post","type-post","status-publish","format-standard","hentry","category-chamber-music","category-vocal","category-work","tag-14","tag-59","tag-18","tag-85","tag-christoph-renhart","tag-dombrowski-stiftungspreis","tag-gaiva-bandzinaite","tag-graz","tag-johanna-von-der-deken","tag-klaudia-tandl","tag-kompositionspreis","tag-mozarteum","tag-nikolaus-fheodoroff-kompositionspreis","tag-palais-meran","tag-radio-oe1","tag-radio-rai","tag-radio-steiermark","tag-salzburg","tag-steiermarkhof","tag-weiz","tag-wolfgang-riegler-sontacchi"],"_links":{"self":[{"href":"https:\/\/www.chrenhart.eu\/2021\/wp-json\/wp\/v2\/posts\/109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chrenhart.eu\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chrenhart.eu\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chrenhart.eu\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chrenhart.eu\/2021\/wp-json\/wp\/v2\/comments?post=109"}],"version-history":[{"count":5,"href":"https:\/\/www.chrenhart.eu\/2021\/wp-json\/wp\/v2\/posts\/109\/revisions"}],"predecessor-version":[{"id":1619,"href":"https:\/\/www.chrenhart.eu\/2021\/wp-json\/wp\/v2\/posts\/109\/revisions\/1619"}],"wp:attachment":[{"href":"https:\/\/www.chrenhart.eu\/2021\/wp-json\/wp\/v2\/media?parent=109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chrenhart.eu\/2021\/wp-json\/wp\/v2\/categories?post=109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chrenhart.eu\/2021\/wp-json\/wp\/v2\/tags?post=109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}